{
    "id": 19105,
    "date": "2022-11-08T02:01:55",
    "date_gmt": "2022-11-08T01:01:55",
    "guid": {
        "rendered": "https:\/\/colorsofmaster.com\/?product=valpaint-sabulador-soft"
    },
    "modified": "2026-07-06T19:41:46",
    "modified_gmt": "2026-07-06T17:41:46",
    "slug": "valpaint-sabulador-soft-32",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/colorsofmaster.com\/fr\/product\/valpaint-sabulador-soft-32\/",
    "title": {
        "rendered": "VALPAINT SABULADOR SOFT"
    },
    "content": {
        "rendered": "<p><em><a href=\"https:\/\/www.colorificiomaster.it\/pdf\/argento-100.pdf\"><i class=\"fas fa-palette\"><\/i><span style=\"text-decoration: underline;\"><strong>\u00a0 \u00a0<\/strong><strong>Silver 100' carte couleur<\/strong><\/span><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.colorificiomaster.it\/pdf\/Sabulador-Soft-Oro-200.pdf\"><i class=\"fas fa-palette\"><\/i><span style=\"text-decoration: underline;\"><strong>\u00a0 \u00a0<\/strong><strong>Carte couleur \"Gold 200<\/strong><\/span><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.colorificiomaster.it\/pdf\/Sabulador-alluminio-300.pdf\"><i class=\"fas fa-palette\"><\/i><span style=\"text-decoration: underline;\"><strong>\u00a0 \u00a0<\/strong><strong>Aluminium 300' carte couleur<\/strong><\/span><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.colorificiomaster.it\/pdf\/bianco-pieno-400.pdf\"><i class=\"fas fa-palette\"><\/i><span style=\"text-decoration: underline;\"><strong>\u00a0 \u00a0<\/strong><strong>Carte de couleur \"Full White 400<\/strong><\/span><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.colorificiomaster.it\/pdf\/gesso-500.pdf\"><i class=\"fas fa-palette\"><\/i><span style=\"text-decoration: underline;\"><strong>\u00a0 \u00a0<\/strong><strong>Carte couleur \"craie 500<\/strong><\/span><\/a><\/em><\/p>\n<p><span style=\"color: #ffffff;\">-<\/span><\/p>\n<p>Il s'agit d'une peinture d'int\u00e9rieur \u00e0 base d'eau avec des reflets de sable sp\u00e9ciaux et luminescents. Sabulador Matt est un produit de haute qualit\u00e9 car il est respirant et peut \u00eatre recouvert par n'importe quelle peinture \u00e0 l'eau. Il est lavable \u00e0 l'eau et avec des d\u00e9tergents courants 15 jours apr\u00e8s son application.<\/p>\n<p>Enlever les vieilles peintures, celles qui se d\u00e9tachent et celles qui s'\u00e9caillent, et les laver avec des savons appropri\u00e9s. Apr\u00e8s s\u00e9chage, remplir et, une fois sec, poncer pour bien lisser la surface. Appliquer ensuite une couche de Primart 600 dilu\u00e9 \u00e0 50% avec de l'eau comme fixateur et apr\u00e8s environ 4 heures \u00e0 20\u00b0C appliquer une deuxi\u00e8me couche de Primart 600 dilu\u00e9 \u00e0 15 - 20%. Si les surfaces sont saines, lisses, non farinantes ou neuves, poncez uniquement l\u00e0 o\u00f9 c'est n\u00e9cessaire pour lisser le support. Appliquer ensuite Primart 600 en une seule couche, dilu\u00e9 \u00e0 15 - 20% avec de l'eau.<\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Avec Sabulador Soft (Lux\/Matt), vous pouvez cr\u00e9er des pi\u00e8ces \u00e9l\u00e9gantes dans des styles modernes et classiques, mais toujours en accord avec les derni\u00e8res tendances. Sabulador est une peinture de qualit\u00e9 car elle est respirante, lavable et peut \u00eatre repeinte avec n'importe quelle peinture \u00e0 l'eau.<\/p>\n<p>Note : Utiliser Primart 600 comme primaire. Voir la fiche : pr\u00e9paration du support.<\/p>\n<p>- Lux Silver 100<br \/>\n- Lux Gold 200<br \/>\n- Lux Aluminium 300<br \/>\n- Lux Full White 400<br \/>\n- Gypse mat 500<\/p>",
        "protected": false
    },
    "featured_media": 27484,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "meta": [],
    "pwb-brand": [],
    "product_brand": [],
    "product_cat": [
        3882,
        3890,
        3875
    ],
    "product_tag": [
        6849
    ],
    "class_list": [
        "post-19105",
        "product",
        "type-product",
        "status-publish",
        "has-post-thumbnail",
        "product_cat-decorativi",
        "product_cat-finiture",
        "product_cat-vernici",
        "product_tag-best-sellers",
        "pa_litri-1-l",
        "pa_litri-25-l",
        "pa_litri-5-l",
        "pa_palette-sabulador-soft-lux",
        "pa_palette-sabulador-soft-matt",
        "first",
        "instock",
        "sale",
        "taxable",
        "shipping-taxable",
        "purchasable",
        "product-type-variable",
        "has-default-attributes"
    ],
    "brands": [
        {
            "id": 3863,
            "name": "Valpaint",
            "slug": "valpaint"
        }
    ],
    "_links": {
        "self": [
            {
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/product\/19105",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/comments?post=19105"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/media\/27484"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/media?parent=19105"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "pwb-brand",
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/pwb-brand?post=19105"
            },
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/product_brand?post=19105"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/product_cat?post=19105"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/colorsofmaster.com\/fr\/wp-json\/wp\/v2\/product_tag?post=19105"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}